{"id":50,"date":"2024-05-07T13:34:59","date_gmt":"2024-05-07T13:34:59","guid":{"rendered":"https:\/\/www.club-z-aero.be\/?page_id=50"},"modified":"2024-05-07T14:06:56","modified_gmt":"2024-05-07T14:06:56","slug":"jai-une-question","status":"publish","type":"page","link":"https:\/\/www.club-z-aero.be\/index.php\/jai-une-question\/","title":{"rendered":"J&#8217;ai une question"},"content":{"rendered":"<div class=\"wpforms-container wpforms-container-full wpforms-block wpforms-block-ff892114-cf31-4320-9a45-c9402e026f7f wpforms-render-modern\" id=\"wpforms-107\"><form id=\"wpforms-form-107\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"107\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/index.php\/wp-json\/wp\/v2\/pages\/50\" data-token=\"4ff382890b0511c2fe1a86b66b5141fc\" data-token-time=\"1778674300\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-107-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><fieldset><legend class=\"wpforms-field-label\">Nom  <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-107-field_0\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][0][first]\" placeholder=\"Nom\" aria-errormessage=\"wpforms-107-field_0-error\" required><label for=\"wpforms-107-field_0\" class=\"wpforms-field-sublabel after\">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-107-field_0-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][0][last]\" placeholder=\"Pr\u00e9nom\" aria-errormessage=\"wpforms-107-field_0-last-error\" required><label for=\"wpforms-107-field_0-last\" class=\"wpforms-field-sublabel after\">Last<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-107-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-107-field_1\">Email <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-107-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" spellcheck=\"false\" aria-errormessage=\"wpforms-107-field_1-error\" required><\/div><div id=\"wpforms-107-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-107-field_2\">Message<\/label><textarea id=\"wpforms-107-field_2\" class=\"wpforms-field-medium\" name=\"wpforms[fields][2]\" aria-errormessage=\"wpforms-107-field_2-error\" ><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"107\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/www.club-z-aero.be\/index.php\/wp-json\/wp\/v2\/pages\/50\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-107\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.club-z-aero.be\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container -->","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-50","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/www.club-z-aero.be\/index.php\/wp-json\/wp\/v2\/pages\/50","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.club-z-aero.be\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.club-z-aero.be\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.club-z-aero.be\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.club-z-aero.be\/index.php\/wp-json\/wp\/v2\/comments?post=50"}],"version-history":[{"count":2,"href":"https:\/\/www.club-z-aero.be\/index.php\/wp-json\/wp\/v2\/pages\/50\/revisions"}],"predecessor-version":[{"id":113,"href":"https:\/\/www.club-z-aero.be\/index.php\/wp-json\/wp\/v2\/pages\/50\/revisions\/113"}],"wp:attachment":[{"href":"https:\/\/www.club-z-aero.be\/index.php\/wp-json\/wp\/v2\/media?parent=50"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}