{"id":38,"date":"2024-05-07T13:33:05","date_gmt":"2024-05-07T13:33:05","guid":{"rendered":"https:\/\/www.club-z-aero.be\/?page_id=38"},"modified":"2024-05-10T08:51:39","modified_gmt":"2024-05-10T08:51:39","slug":"2023-10-21-22","status":"publish","type":"page","link":"https:\/\/www.club-z-aero.be\/index.php\/2023-10-21-22\/","title":{"rendered":"2023 10 21-22"},"content":{"rendered":"\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/www.club-z-aero.be\/wp-content\/uploads\/2024\/05\/2023-10-21-724x1024.jpg\" alt=\"\" class=\"wp-image-301\" srcset=\"https:\/\/www.club-z-aero.be\/wp-content\/uploads\/2024\/05\/2023-10-21-724x1024.jpg 724w, https:\/\/www.club-z-aero.be\/wp-content\/uploads\/2024\/05\/2023-10-21-212x300.jpg 212w, https:\/\/www.club-z-aero.be\/wp-content\/uploads\/2024\/05\/2023-10-21-768x1086.jpg 768w, https:\/\/www.club-z-aero.be\/wp-content\/uploads\/2024\/05\/2023-10-21-1086x1536.jpg 1086w, https:\/\/www.club-z-aero.be\/wp-content\/uploads\/2024\/05\/2023-10-21-1448x2048.jpg 1448w, https:\/\/www.club-z-aero.be\/wp-content\/uploads\/2024\/05\/2023-10-21-scaled.jpg 1810w\" sizes=\"auto, (max-width: 724px) 100vw, 724px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p>Album Photos<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Album Photos<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-38","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/www.club-z-aero.be\/index.php\/wp-json\/wp\/v2\/pages\/38","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.club-z-aero.be\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.club-z-aero.be\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.club-z-aero.be\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.club-z-aero.be\/index.php\/wp-json\/wp\/v2\/comments?post=38"}],"version-history":[{"count":3,"href":"https:\/\/www.club-z-aero.be\/index.php\/wp-json\/wp\/v2\/pages\/38\/revisions"}],"predecessor-version":[{"id":306,"href":"https:\/\/www.club-z-aero.be\/index.php\/wp-json\/wp\/v2\/pages\/38\/revisions\/306"}],"wp:attachment":[{"href":"https:\/\/www.club-z-aero.be\/index.php\/wp-json\/wp\/v2\/media?parent=38"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}